{"id":9400,"date":"2024-09-10T08:47:07","date_gmt":"2024-09-10T06:47:07","guid":{"rendered":"https:\/\/forfulgtekristne.dk\/?post_type=product&#038;p=9400"},"modified":"2026-04-24T16:54:42","modified_gmt":"2026-04-24T14:54:42","slug":"the-new-testament-in-arabic-and-english","status":"publish","type":"product","link":"https:\/\/forfulgtekristne.dk\/en\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/","title":{"rendered":"The New Testament in Arabic and English"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":9401,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[600,601],"product_tag":[],"class_list":["post-9400","product","type-product","status-publish","has-post-thumbnail","product_cat-bibler","product_cat-boeger","infinite-scroll-item","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Det Nye Testamente p\u00e5 arabisk og engelsk | Dansk Europamission<\/title>\n<meta name=\"description\" content=\"Det Nye Testamente p\u00e5 arabisk og engelsk\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forfulgtekristne.dk\/en\/product-2\/the-new-testament-in-arabic-and-english\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Det Nye Testamente p\u00e5 arabisk og engelsk | Dansk Europamission\" \/>\n<meta property=\"og:description\" content=\"Det Nye Testamente p\u00e5 arabisk og engelsk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forfulgtekristne.dk\/en\/product-2\/the-new-testament-in-arabic-and-english\/\" \/>\n<meta property=\"og:site_name\" content=\"Dansk Europamission\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T14:54:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forfulgtekristne.dk\/wp-content\/uploads\/2024\/09\/Skaermbillede-2024-09-10-kl.-08.45.03.png\" \/>\n\t<meta property=\"og:image:width\" content=\"752\" \/>\n\t<meta property=\"og:image:height\" content=\"1088\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/produkt\\\/det-nye-testamente-paa-arabisk-og-engelsk\\\/\",\"url\":\"https:\\\/\\\/forfulgtekristne.dk\\\/produkt\\\/det-nye-testamente-paa-arabisk-og-engelsk\\\/\",\"name\":\"Det Nye Testamente p\u00e5 arabisk og engelsk | Dansk Europamission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/produkt\\\/det-nye-testamente-paa-arabisk-og-engelsk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/produkt\\\/det-nye-testamente-paa-arabisk-og-engelsk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forfulgtekristne.dk\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Skaermbillede-2024-09-10-kl.-08.45.03.png\",\"datePublished\":\"2024-09-10T06:47:07+00:00\",\"dateModified\":\"2026-04-24T14:54:42+00:00\",\"description\":\"Det Nye Testamente p\u00e5 arabisk og engelsk\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/produkt\\\/det-nye-testamente-paa-arabisk-og-engelsk\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/forfulgtekristne.dk\\\/produkt\\\/det-nye-testamente-paa-arabisk-og-engelsk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/produkt\\\/det-nye-testamente-paa-arabisk-og-engelsk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forfulgtekristne.dk\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Skaermbillede-2024-09-10-kl.-08.45.03.png\",\"contentUrl\":\"https:\\\/\\\/forfulgtekristne.dk\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Skaermbillede-2024-09-10-kl.-08.45.03.png\",\"width\":752,\"height\":1088,\"caption\":\"Det Nye Testamente p\u00e5 arabisk og engelsk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/produkt\\\/det-nye-testamente-paa-arabisk-og-engelsk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/forfulgtekristne.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webbutik\",\"item\":\"https:\\\/\\\/forfulgtekristne.dk\\\/butik\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Det Nye Testamente p\u00e5 arabisk og engelsk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/#website\",\"url\":\"https:\\\/\\\/forfulgtekristne.dk\\\/\",\"name\":\"Dansk Europamission\",\"description\":\"Hj\u00e6lp til forfulgte kristne - evangeliet til un\u00e5ede\",\"publisher\":{\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forfulgtekristne.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/#organization\",\"name\":\"Dansk Europamission\",\"url\":\"https:\\\/\\\/forfulgtekristne.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forfulgtekristne.dk\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Logo-Dansk-Europamission.svg\",\"contentUrl\":\"https:\\\/\\\/forfulgtekristne.dk\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Logo-Dansk-Europamission.svg\",\"caption\":\"Dansk Europamission\"},\"image\":{\"@id\":\"https:\\\/\\\/forfulgtekristne.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The New Testament in Arabic and English | Danish European Mission","description":"The New Testament in Arabic and English","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forfulgtekristne.dk\/en\/product-2\/the-new-testament-in-arabic-and-english\/","og_locale":"en_US","og_type":"article","og_title":"Det Nye Testamente p\u00e5 arabisk og engelsk | Dansk Europamission","og_description":"Det Nye Testamente p\u00e5 arabisk og engelsk","og_url":"https:\/\/forfulgtekristne.dk\/en\/product-2\/the-new-testament-in-arabic-and-english\/","og_site_name":"Dansk Europamission","article_modified_time":"2026-04-24T14:54:42+00:00","og_image":[{"width":752,"height":1088,"url":"https:\/\/forfulgtekristne.dk\/wp-content\/uploads\/2024\/09\/Skaermbillede-2024-09-10-kl.-08.45.03.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forfulgtekristne.dk\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/","url":"https:\/\/forfulgtekristne.dk\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/","name":"The New Testament in Arabic and English | Danish European Mission","isPartOf":{"@id":"https:\/\/forfulgtekristne.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forfulgtekristne.dk\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/#primaryimage"},"image":{"@id":"https:\/\/forfulgtekristne.dk\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/#primaryimage"},"thumbnailUrl":"https:\/\/forfulgtekristne.dk\/wp-content\/uploads\/2024\/09\/Skaermbillede-2024-09-10-kl.-08.45.03.png","datePublished":"2024-09-10T06:47:07+00:00","dateModified":"2026-04-24T14:54:42+00:00","description":"The New Testament in Arabic and English","breadcrumb":{"@id":"https:\/\/forfulgtekristne.dk\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forfulgtekristne.dk\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/forfulgtekristne.dk\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/#primaryimage","url":"https:\/\/forfulgtekristne.dk\/wp-content\/uploads\/2024\/09\/Skaermbillede-2024-09-10-kl.-08.45.03.png","contentUrl":"https:\/\/forfulgtekristne.dk\/wp-content\/uploads\/2024\/09\/Skaermbillede-2024-09-10-kl.-08.45.03.png","width":752,"height":1088,"caption":"Det Nye Testamente p\u00e5 arabisk og engelsk"},{"@type":"BreadcrumbList","@id":"https:\/\/forfulgtekristne.dk\/produkt\/det-nye-testamente-paa-arabisk-og-engelsk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/forfulgtekristne.dk\/"},{"@type":"ListItem","position":2,"name":"Webbutik","item":"https:\/\/forfulgtekristne.dk\/butik\/"},{"@type":"ListItem","position":3,"name":"Det Nye Testamente p\u00e5 arabisk og engelsk"}]},{"@type":"WebSite","@id":"https:\/\/forfulgtekristne.dk\/#website","url":"https:\/\/forfulgtekristne.dk\/","name":"Mission Possible","description":"Helping persecuted Christians - the gospel to the unreached","publisher":{"@id":"https:\/\/forfulgtekristne.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forfulgtekristne.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/forfulgtekristne.dk\/#organization","name":"Mission Possible","url":"https:\/\/forfulgtekristne.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/forfulgtekristne.dk\/#\/schema\/logo\/image\/","url":"https:\/\/forfulgtekristne.dk\/wp-content\/uploads\/2025\/01\/Logo-Dansk-Europamission.svg","contentUrl":"https:\/\/forfulgtekristne.dk\/wp-content\/uploads\/2025\/01\/Logo-Dansk-Europamission.svg","caption":"Dansk Europamission"},"image":{"@id":"https:\/\/forfulgtekristne.dk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forfulgtekristne.dk\/en\/wp-json\/wp\/v2\/product\/9400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forfulgtekristne.dk\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/forfulgtekristne.dk\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forfulgtekristne.dk\/en\/wp-json\/wp\/v2\/media\/9401"}],"wp:attachment":[{"href":"https:\/\/forfulgtekristne.dk\/en\/wp-json\/wp\/v2\/media?parent=9400"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/forfulgtekristne.dk\/en\/wp-json\/wp\/v2\/product_brand?post=9400"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/forfulgtekristne.dk\/en\/wp-json\/wp\/v2\/product_cat?post=9400"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/forfulgtekristne.dk\/en\/wp-json\/wp\/v2\/product_tag?post=9400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}